{"id":1248,"date":"2019-10-31T08:44:58","date_gmt":"2019-10-31T07:44:58","guid":{"rendered":"https:\/\/www.galsila.it\/site\/?p=1248"},"modified":"2020-02-05T17:09:27","modified_gmt":"2020-02-05T16:09:27","slug":"decreto-di-proroga-dei-termini-di-scadenza-dellavviso-pubblico-del-gal-sila-sviluppo-relativo-allintervento-6-2-1","status":"publish","type":"post","link":"https:\/\/www.galsila.it\/site\/2019\/10\/decreto-di-proroga-dei-termini-di-scadenza-dellavviso-pubblico-del-gal-sila-sviluppo-relativo-allintervento-6-2-1\/","title":{"rendered":"Decreto di proroga dei termini di scadenza dell&#8217;avviso pubblico del Gal Sila Sviluppo relativo all&#8217;intervento 6.2.1"},"content":{"rendered":"<p>Decreto di proroga dei termini di scadenza dell&#8217;avviso pubblico del Gal Sila Sviluppo relativo all&#8217;intervento 6.2.1.\u00a0La scadenza del 31.10.2019 viene prorogata all&#8217;11.11.2019<\/p>\n<p>Allegati<\/p>\n<p><a href=\"https:\/\/www.galsila.it\/site\/wp-content\/uploads\/2019\/10\/Decreto-n.-28-2019-di-proroga-bando-6.2.1.pdf\">Decreto n. 28- 2019 di proroga bando 6.2.1<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Decreto di proroga dei termini di scadenza dell&#8217;avviso pubblico del Gal Sila Sviluppo relativo all&#8217;intervento 6.2.1.\u00a0La scadenza del 31.10.2019 viene prorogata all&#8217;11.11.2019 Allegati Decreto n. 28- 2019 di proroga bando [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mo_disable_npp":"","ngg_post_thumbnail":0,"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-1248","post","type-post","status-publish","format-standard","hentry","category-proroga"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 20:49:57","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.galsila.it\/site\/wp-json\/wp\/v2\/posts\/1248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.galsila.it\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.galsila.it\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.galsila.it\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.galsila.it\/site\/wp-json\/wp\/v2\/comments?post=1248"}],"version-history":[{"count":2,"href":"https:\/\/www.galsila.it\/site\/wp-json\/wp\/v2\/posts\/1248\/revisions"}],"predecessor-version":[{"id":1258,"href":"https:\/\/www.galsila.it\/site\/wp-json\/wp\/v2\/posts\/1248\/revisions\/1258"}],"wp:attachment":[{"href":"https:\/\/www.galsila.it\/site\/wp-json\/wp\/v2\/media?parent=1248"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.galsila.it\/site\/wp-json\/wp\/v2\/categories?post=1248"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.galsila.it\/site\/wp-json\/wp\/v2\/tags?post=1248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}